{"id":1264,"date":"2023-07-24T19:28:25","date_gmt":"2023-07-24T17:28:25","guid":{"rendered":"http:\/\/jeanclaudefaujour.com\/?page_id=1264"},"modified":"2023-07-27T17:48:57","modified_gmt":"2023-07-27T15:48:57","slug":"archeologie-mental-am-2d","status":"publish","type":"page","link":"https:\/\/jeanclaudefaujour.com\/index.php\/archeologie-mental-am-2d\/","title":{"rendered":"Arch\u00e9ologie Mentale : AM 2D &#8211; 2001"},"content":{"rendered":"<p>en 2 dimensions<\/p>\n<figure id=\"attachment_1274\" aria-describedby=\"caption-attachment-1274\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/jeanclaudefaujour.com\/wp-content\/uploads\/2023\/07\/AM-Amour.jpg\" target=\"_blank\" rel=\"attachment noopener wp-att-1274\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1274 size-medium\" src=\"https:\/\/jeanclaudefaujour.com\/wp-content\/uploads\/2023\/07\/AM-Amour-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/jeanclaudefaujour.com\/wp-content\/uploads\/2023\/07\/AM-Amour-300x300.jpg 300w, https:\/\/jeanclaudefaujour.com\/wp-content\/uploads\/2023\/07\/AM-Amour-150x150.jpg 150w, https:\/\/jeanclaudefaujour.com\/wp-content\/uploads\/2023\/07\/AM-Amour-100x100.jpg 100w, https:\/\/jeanclaudefaujour.com\/wp-content\/uploads\/2023\/07\/AM-Amour.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-1274\" class=\"wp-caption-text\">AM Amour<\/figcaption><\/figure>\n<figure id=\"attachment_1275\" aria-describedby=\"caption-attachment-1275\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/jeanclaudefaujour.com\/wp-content\/uploads\/2023\/07\/AM-Ciel.jpg\" target=\"_blank\" rel=\"attachment noopener wp-att-1275\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1275 size-medium\" src=\"https:\/\/jeanclaudefaujour.com\/wp-content\/uploads\/2023\/07\/AM-Ciel-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/jeanclaudefaujour.com\/wp-content\/uploads\/2023\/07\/AM-Ciel-300x300.jpg 300w, https:\/\/jeanclaudefaujour.com\/wp-content\/uploads\/2023\/07\/AM-Ciel-150x150.jpg 150w, https:\/\/jeanclaudefaujour.com\/wp-content\/uploads\/2023\/07\/AM-Ciel-100x100.jpg 100w, https:\/\/jeanclaudefaujour.com\/wp-content\/uploads\/2023\/07\/AM-Ciel.jpg 602w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-1275\" class=\"wp-caption-text\">AM Ciel<\/figcaption><\/figure>\n<figure id=\"attachment_1277\" aria-describedby=\"caption-attachment-1277\" style=\"width: 241px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/jeanclaudefaujour.com\/wp-content\/uploads\/2023\/07\/AM-creuser.jpg\" target=\"_blank\" rel=\"attachment noopener wp-att-1277\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1277 size-medium\" src=\"https:\/\/jeanclaudefaujour.com\/wp-content\/uploads\/2023\/07\/AM-creuser-241x300.jpg\" alt=\"\" width=\"241\" height=\"300\" srcset=\"https:\/\/jeanclaudefaujour.com\/wp-content\/uploads\/2023\/07\/AM-creuser-241x300.jpg 241w, https:\/\/jeanclaudefaujour.com\/wp-content\/uploads\/2023\/07\/AM-creuser.jpg 481w\" sizes=\"auto, (max-width: 241px) 100vw, 241px\" \/><\/a><figcaption id=\"caption-attachment-1277\" class=\"wp-caption-text\">AM creuser<\/figcaption><\/figure>\n<figure id=\"attachment_1279\" aria-describedby=\"caption-attachment-1279\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/jeanclaudefaujour.com\/wp-content\/uploads\/2023\/07\/AM-ivern.jpg\" target=\"_blank\" rel=\"attachment noopener wp-att-1279\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1279 size-medium\" src=\"https:\/\/jeanclaudefaujour.com\/wp-content\/uploads\/2023\/07\/AM-ivern-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/jeanclaudefaujour.com\/wp-content\/uploads\/2023\/07\/AM-ivern-300x300.jpg 300w, https:\/\/jeanclaudefaujour.com\/wp-content\/uploads\/2023\/07\/AM-ivern-150x150.jpg 150w, https:\/\/jeanclaudefaujour.com\/wp-content\/uploads\/2023\/07\/AM-ivern-100x100.jpg 100w, https:\/\/jeanclaudefaujour.com\/wp-content\/uploads\/2023\/07\/AM-ivern.jpg 602w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-1279\" class=\"wp-caption-text\">AM ivern<\/figcaption><\/figure>\n<figure id=\"attachment_1280\" aria-describedby=\"caption-attachment-1280\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/jeanclaudefaujour.com\/wp-content\/uploads\/2023\/07\/AM-Signes.jpg\" target=\"_blank\" rel=\"attachment noopener wp-att-1280\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1280 size-medium\" src=\"https:\/\/jeanclaudefaujour.com\/wp-content\/uploads\/2023\/07\/AM-Signes-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/jeanclaudefaujour.com\/wp-content\/uploads\/2023\/07\/AM-Signes-300x300.jpg 300w, https:\/\/jeanclaudefaujour.com\/wp-content\/uploads\/2023\/07\/AM-Signes-150x150.jpg 150w, https:\/\/jeanclaudefaujour.com\/wp-content\/uploads\/2023\/07\/AM-Signes-100x100.jpg 100w, https:\/\/jeanclaudefaujour.com\/wp-content\/uploads\/2023\/07\/AM-Signes.jpg 599w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-1280\" class=\"wp-caption-text\">AM Signes<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>en 2 dimensions<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1264","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arch\u00e9ologie Mentale : AM 2D - 2001 - Jean-Claude Faujour<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arch\u00e9ologie Mentale : AM 2D - 2001 - Jean-Claude Faujour\" \/>\n<meta property=\"og:description\" content=\"en 2 dimensions\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jeanclaudefaujour.com\/index.php\/archeologie-mental-am-2d\/\" \/>\n<meta property=\"og:site_name\" content=\"Jean-Claude Faujour\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-27T15:48:57+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/jeanclaudefaujour.com\/wp-content\/uploads\/2023\/07\/AM-Amour-300x300.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jeanclaudefaujour.com\\\/index.php\\\/archeologie-mental-am-2d\\\/\",\"url\":\"https:\\\/\\\/jeanclaudefaujour.com\\\/index.php\\\/archeologie-mental-am-2d\\\/\",\"name\":\"Arch\u00e9ologie Mentale : AM 2D - 2001 - Jean-Claude Faujour\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jeanclaudefaujour.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jeanclaudefaujour.com\\\/index.php\\\/archeologie-mental-am-2d\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jeanclaudefaujour.com\\\/index.php\\\/archeologie-mental-am-2d\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/jeanclaudefaujour.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/AM-Amour-300x300.jpg\",\"datePublished\":\"2023-07-24T17:28:25+00:00\",\"dateModified\":\"2023-07-27T15:48:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jeanclaudefaujour.com\\\/index.php\\\/archeologie-mental-am-2d\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jeanclaudefaujour.com\\\/index.php\\\/archeologie-mental-am-2d\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jeanclaudefaujour.com\\\/index.php\\\/archeologie-mental-am-2d\\\/#primaryimage\",\"url\":\"http:\\\/\\\/jeanclaudefaujour.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/AM-Amour-300x300.jpg\",\"contentUrl\":\"http:\\\/\\\/jeanclaudefaujour.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/AM-Amour-300x300.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jeanclaudefaujour.com\\\/index.php\\\/archeologie-mental-am-2d\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/jeanclaudefaujour.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arch\u00e9ologie Mentale : AM 2D &#8211; 2001\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jeanclaudefaujour.com\\\/#website\",\"url\":\"https:\\\/\\\/jeanclaudefaujour.com\\\/\",\"name\":\"Jean-Claude Faujour\",\"description\":\"tous droits r\u00e9serv\u00e9s\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jeanclaudefaujour.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arch\u00e9ologie Mentale : AM 2D - 2001 - Jean-Claude Faujour","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Arch\u00e9ologie Mentale : AM 2D - 2001 - Jean-Claude Faujour","og_description":"en 2 dimensions","og_url":"https:\/\/jeanclaudefaujour.com\/index.php\/archeologie-mental-am-2d\/","og_site_name":"Jean-Claude Faujour","article_modified_time":"2023-07-27T15:48:57+00:00","og_image":[{"url":"http:\/\/jeanclaudefaujour.com\/wp-content\/uploads\/2023\/07\/AM-Amour-300x300.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/jeanclaudefaujour.com\/index.php\/archeologie-mental-am-2d\/","url":"https:\/\/jeanclaudefaujour.com\/index.php\/archeologie-mental-am-2d\/","name":"Arch\u00e9ologie Mentale : AM 2D - 2001 - Jean-Claude Faujour","isPartOf":{"@id":"https:\/\/jeanclaudefaujour.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jeanclaudefaujour.com\/index.php\/archeologie-mental-am-2d\/#primaryimage"},"image":{"@id":"https:\/\/jeanclaudefaujour.com\/index.php\/archeologie-mental-am-2d\/#primaryimage"},"thumbnailUrl":"http:\/\/jeanclaudefaujour.com\/wp-content\/uploads\/2023\/07\/AM-Amour-300x300.jpg","datePublished":"2023-07-24T17:28:25+00:00","dateModified":"2023-07-27T15:48:57+00:00","breadcrumb":{"@id":"https:\/\/jeanclaudefaujour.com\/index.php\/archeologie-mental-am-2d\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jeanclaudefaujour.com\/index.php\/archeologie-mental-am-2d\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jeanclaudefaujour.com\/index.php\/archeologie-mental-am-2d\/#primaryimage","url":"http:\/\/jeanclaudefaujour.com\/wp-content\/uploads\/2023\/07\/AM-Amour-300x300.jpg","contentUrl":"http:\/\/jeanclaudefaujour.com\/wp-content\/uploads\/2023\/07\/AM-Amour-300x300.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/jeanclaudefaujour.com\/index.php\/archeologie-mental-am-2d\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/jeanclaudefaujour.com\/"},{"@type":"ListItem","position":2,"name":"Arch\u00e9ologie Mentale : AM 2D &#8211; 2001"}]},{"@type":"WebSite","@id":"https:\/\/jeanclaudefaujour.com\/#website","url":"https:\/\/jeanclaudefaujour.com\/","name":"Jean-Claude Faujour","description":"tous droits r\u00e9serv\u00e9s","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jeanclaudefaujour.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/jeanclaudefaujour.com\/index.php\/wp-json\/wp\/v2\/pages\/1264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jeanclaudefaujour.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/jeanclaudefaujour.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/jeanclaudefaujour.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jeanclaudefaujour.com\/index.php\/wp-json\/wp\/v2\/comments?post=1264"}],"version-history":[{"count":6,"href":"https:\/\/jeanclaudefaujour.com\/index.php\/wp-json\/wp\/v2\/pages\/1264\/revisions"}],"predecessor-version":[{"id":1505,"href":"https:\/\/jeanclaudefaujour.com\/index.php\/wp-json\/wp\/v2\/pages\/1264\/revisions\/1505"}],"wp:attachment":[{"href":"https:\/\/jeanclaudefaujour.com\/index.php\/wp-json\/wp\/v2\/media?parent=1264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}